{"id":1165,"date":"2015-11-10T20:41:02","date_gmt":"2015-11-10T19:41:02","guid":{"rendered":"http:\/\/recherche-action.fr\/hugues-bazin\/?p=1165"},"modified":"2015-11-10T20:41:02","modified_gmt":"2015-11-10T19:41:02","slug":"assises-des-cultures-urbaines-3eme-edition-paris-20e","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/hugues-bazin\/2015\/11\/10\/assises-des-cultures-urbaines-3eme-edition-paris-20e\/","title":{"rendered":"Assises du hip-hop (3eme \u00e9dition, Paris 20e)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/recherche-action.fr\/hugues-bazin\/2015\/11\/10\/assises-des-cultures-urbaines-3eme-edition-paris-20e\/#Inscriptions\" >Inscriptions<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/recherche-action.fr\/hugues-bazin\/2015\/11\/10\/assises-des-cultures-urbaines-3eme-edition-paris-20e\/#A_quoi_ca_sert_les_Assises_du_Hip_Hop\" >A quoi \u00e7a sert les Assises du Hip Hop ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/recherche-action.fr\/hugues-bazin\/2015\/11\/10\/assises-des-cultures-urbaines-3eme-edition-paris-20e\/#Comment_sont_nees_les_Assises\" >Comment sont n\u00e9es les Assises ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/recherche-action.fr\/hugues-bazin\/2015\/11\/10\/assises-des-cultures-urbaines-3eme-edition-paris-20e\/#Comment_cette_3eme_edition_est_construite\" >Comment cette 3\u00e9me \u00e9dition est construite ?<\/a><\/li><\/ul><\/nav><\/div>\n<h3>Assises du hip-hop (3eme \u00e9dition, Paris 20e)<\/h3>\n<p>organis\u00e9es par l&rsquo;association <a href=\"http:\/\/metissage94.fr\/assises-du-hip-hop-2015\/\" target=\"_blank\">M\u00e9tissage <\/a>en partenariat avec le <a href=\"http:\/\/recherche-action.fr\/labo-social\/\" target=\"_blank\">LISRA<\/a><\/p>\n<h3><strong><span style=\"color: #008000\">Vendredi 4 d\u00e9cembre 2015 de 9h30 \u00e0 20h<a style=\"color: #008000\" href=\"https:\/\/recherche-action.fr\/hugues-bazin\/files\/2015\/11\/12193506_979557222101576_7897317813338435335_n.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-1166\" src=\"https:\/\/recherche-action.fr\/hugues-bazin\/files\/2015\/11\/12193506_979557222101576_7897317813338435335_n.jpg\" alt=\"12193506_979557222101576_7897317813338435335_n\" width=\"357\" height=\"509\" \/><\/a><\/span><\/strong><\/h3>\n<p><strong><span style=\"color: #008000\">Centre ken saro wiwa<\/span><span style=\"color: #008000\"><strong>,<\/strong> 68 rue Buzenval, 75020 Paris, (M\u00b09 Buzenval)<\/span><\/strong><\/p>\n<p>Au programme :<\/p>\n<ul>\n<li>9h30 : Accueil des participants<\/li>\n<li>10h00 : Pr\u00e9sentation de la d\u00e9marche et orientations de cette 3\u00e8me \u00e9dition<\/li>\n<li>10h15 : Chantier de r\u00e9flexion :<br \/>\n&gt; Concertation autour de mati\u00e8res premi\u00e8res rassembl\u00e9es suite \u00e0 l\u2019appel \u00e0 textes<br \/>\n&gt; D\u00e9finition collective des diff\u00e9rentes th\u00e9matiques de l\u2019apr\u00e8s-midi<\/li>\n<li>12h30 : Fresh Urban Food by Cuisine &amp; Nutrition \u00ab\u00a0Je mange donc je suis\u201d : alimentation \u00e9nerg\u00e9tique, produits de saison, cuisine maison\u2026 (5\u20ac lors de l\u2019inscription, 8\u20ac sur place)<\/li>\n<li>14h : Groupes de co-construction th\u00e9matique et recherches d\u2019actions concr\u00e8tes<\/li>\n<li>16h30 : Restitution en pl\u00e9ni\u00e8re des r\u00e9flexions et plan d&rsquo;actions<\/li>\n<li>18h30 : Cl\u00f4ture et ap\u00e9ro-concert<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Inscriptions\"><\/span>Inscriptions<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&rsquo;entr\u00e9e est gratuite et l&rsquo;inscription obligatoire <a href=\"http:\/\/goo.gl\/forms\/F02Ha6G7L2\" target=\"_blank\">ici<\/a><\/p>\n<p>Pour le repas vous b\u00e9n\u00e9ficiez d&rsquo;un tarif pr\u00e9f\u00e9rentiel en <a href=\"https:\/\/www.paypal.me\/repasassises\" target=\"_blank\">payant votre repas \u00e0 l&rsquo;avance ici<\/a> jusqu&rsquo;au 2 d\u00e9cembre<br \/>\n(Indiquez 5\u20ac dans la case). Sur place le tarif est de 8\u20ac (nous ne pourrons pas garantir un repas \u00e0 tous les non-inscrits).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_quoi_ca_sert_les_Assises_du_Hip_Hop\"><\/span>A quoi \u00e7a sert les Assises du Hip Hop ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Chacun(e) \u00e0 ses raisons&#8230; Globalement elles permettent de penser sa pratique, d\u2019\u00e9changer sur les diverses exp\u00e9rimentations des uns et des autres.<\/p>\n<p>En partageant ses id\u00e9es nous nous donnons l\u2019opportunit\u00e9 de les affiner, les contredire ou les valider. C\u2019est remettre en cause ce qu\u2019on conna\u00eet et ne pas retomber dans \u00ab l\u2019us\u00e9 \u00bb. Penser, c\u2019est aussi comprendre les enjeux, s\u2019adapter aux r\u00e9alit\u00e9s du moment, \u00e9voluer et imaginer d\u2019autres possibles pour demain.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_sont_nees_les_Assises\"><\/span>Comment sont n\u00e9es les Assises ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les Assises du Hip Hop sont n\u00e9es en 2011 \u00e0 la suite d\u2019un diagnostic partag\u00e9. Afin de r\u00e9fl\u00e9chir cette culture, des sp\u00e9cialistes sont venus expliquer au public leurs savoirs. Nous avons pris alors conscience que les meilleurs experts sont ceux qui pratiquent leurs arts. Nous avons donc confi\u00e9 la parole aux acteurs eux-m\u00eames lors de la 2\u00e9me \u00e9dition en s\u2019inspirant du concept de recherche-action et de la collaboration avec Hugues Bazin.<\/p>\n<p>Pour la 3\u00e9me \u00e9dition, nous la voulons cette fois enti\u00e8rement co-construite, reposant sur l\u2019\u00e9change et le partage.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_cette_3eme_edition_est_construite\"><\/span>Comment cette 3\u00e9me \u00e9dition est construite ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>D\u00e8s la phase de conception et de pr\u00e9paration des Assises les acteurs se sont mobilis\u00e9s. D\u2019abord pens\u00e9 au niveau r\u00e9gional, l\u2019engouement a finalement touch\u00e9 le territoire national ! Nous imaginons ensemble ce laboratoire gr\u00e2ce \u00e0 des outils collaboratifs et partageons les ressources pour vivre ce v\u00e9ritable Think Tank du Hip Hop !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assises du hip-hop (3eme \u00e9dition, Paris 20e) organis\u00e9es par l&rsquo;association M\u00e9tissage en partenariat avec le LISRA Vendredi 4 d\u00e9cembre 2015 de 9h30 \u00e0 20h Centre ken saro wiwa, 68 rue Buzenval, 75020 Paris, (M\u00b09 Buzenval) Au programme : 9h30 : Accueil des participants 10h00 : Pr\u00e9sentation de la d\u00e9marche et orientations &hellip; <\/p>\n","protected":false},"author":1,"featured_media":1166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[3],"tags":[5,11,12,13,14,16,25,30,31,33,44,45,48,50,52,76],"class_list":["post-1165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intervention","tag-action-culturelle","tag-art-de-la-rue","tag-art-social","tag-atelier-artistique","tag-atelier-recherche-action","tag-banlieue","tag-citoyennete","tag-danse","tag-developpement-culturel","tag-diversite-culturelle","tag-expression-artistique","tag-formation-action","tag-graffiti","tag-hip-hop","tag-ile-de-france","tag-rap"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2QGRI-iN","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":0,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}