{"id":2223,"date":"2018-07-13T18:42:49","date_gmt":"2018-07-13T16:42:49","guid":{"rendered":"http:\/\/recherche-action.fr\/hugues-bazin\/?p=2223"},"modified":"2018-07-13T19:30:39","modified_gmt":"2018-07-13T17:30:39","slug":"illegalite-et-recherche-action","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/hugues-bazin\/2018\/07\/13\/illegalite-et-recherche-action\/","title":{"rendered":"Ill\u00e9galit\u00e9 et recherche-action"},"content":{"rendered":"<p>Intervention du LISRA au colloque sur les recherches participatives avec des groupes d\u00e9viants, stigmatis\u00e9s, marginalis\u00e9s. quelles approches th\u00e9oriques, pratiques et d\u00e9ontologiques ? (1)<\/p>\n<p>Jeudi 13 septembre 2018 de 11h \u00e0 13h<br \/>\nCentre de Formation Saint-Honor\u00e9<br \/>\n42-44 Rue de Romainville &#8211; 75019 Paris<a href=\"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2018\/07\/arton3822.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-2224\" src=\"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2018\/07\/arton3822.jpg\" alt=\"\" width=\"344\" height=\"242\" srcset=\"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2018\/07\/arton3822.jpg 653w, https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2018\/07\/arton3822-300x210.jpg 300w\" sizes=\"(max-width: 344px) 100vw, 344px\" \/><\/a><\/p>\n<p>Notre laboratoire social travaille avec des r\u00e9cup\u00e9rateurs vendeurs de rue, des vendeurs ambulants, des Roms, des habitants en squat d\u2019urgence dont les pratiques sont soumises \u00e0 la r\u00e9pression sociale et polici\u00e8re. Nous rencontrons des difficult\u00e9s lorsqu\u2019il s\u2019agit de probl\u00e9matiser leur pratique d\u2019\u00e9conomie populaire aussi bien dans le domaine de la recherche que de l\u2019action publique.<\/p>\n<p>On parlera alors de pratiques \u00ab\u00a0grises\u00a0\u00bb, \u00ab\u00a0informelles\u00a0\u00bb, \u00ab\u00a0sauvages\u00a0\u00bb qui sous un caract\u00e8re technique confortent et confirment une ethnicisation de l\u2019ill\u00e9galit\u00e9. Nous entendons par l\u00e0 que la rh\u00e9torique des \u00ab\u00a0territoires de non-droit\u00a0\u00bb ne d\u00e9signe pas seulement une pratique ill\u00e9gale selon un droit positif, mais participe d\u2019une construction sociale de la fronti\u00e8re au-del\u00e0 de laquelle peuvent intervenir en toute impunit\u00e9 les d\u00e9positaires l\u00e9gaux de l\u2019ordre social et de la violence l\u00e9gitime. La criminalisation de la pauvret\u00e9, le d\u00e9lit de solidarit\u00e9 au migrant ou l\u2019\u00e9vacuation des bidonvilles roms participe de ce processus.<\/p>\n<p>Que veut dire dans ces conditions la \u00ab\u00a0participation\u00a0\u00bb de populations assign\u00e9es \u00e0 un non-lieu d\u2019o\u00f9 elles ne peuvent d\u2019aucune mani\u00e8re se constituer en hors-lieux, c&rsquo;est-\u00e0-dire en minorit\u00e9 active. Les acteurs sociaux ne peuvent avoir une place comme co-auteurs d\u2019une recherche-action s\u2019ils sont d\u00e9j\u00e0 construits socialement par la recherche en tant que corps dociles et \u00e9trangers.<\/p>\n<p>Pour que les chercheurs puissent probl\u00e9matiser la non-parole d\u2019une non-existence, ils doivent eux-m\u00eames se constituer un hors-lieux transfrontalier. Ce qui induit un renversement axiologique, une \u00e9pist\u00e9mologie de l\u2019absence pour identifier ce vide ou se manque qui r\u00e9duit et \u00e9touffe la r\u00e9alit\u00e9 sociale. Sinon la participation n\u2019est qu\u2019une id\u00e9ologie qui construit l\u2019autre dans sa diff\u00e9rence irr\u00e9ductible de non-chercheur, objet d\u2019\u00e9tude, simples pourvoyeurs de mat\u00e9riaux.<\/p>\n<p>Nous rejoignions ici la proposition d\u2019une \u00ab\u00a0\u00e9pist\u00e9mologie du Sud\u00a0\u00bb : il ne peut avoir de justice sociale globale sans justice cognitive globale, c\u2019est-\u00e0-dire sans reconnaissance de la pluralit\u00e9 des savoirs, notamment ceux issus de la pratique et de l\u2019exp\u00e9rience.<\/p>\n<p>(1) Colloque international organis\u00e9 par le R\u00e9seau Th\u00e9matique 3 \u00ab Normes, d\u00e9viances et r\u00e9actions sociales \u00bb de l\u2019Association fran\u00e7aise de sociologie (AFS), le Centre d\u2019Etude et de Recherche Appliqu\u00e9es (CERA) et l\u2019Association des Chercheurs des Organismes de la Formation et de l&rsquo;Intervention Sociales (<a href=\"http:\/\/www.acofis.org\/component\/content\/article\/455-2018-07-13-14-00-11.html\" target=\"_blank\" rel=\"noopener\">ACOFIS<\/a>)<\/p>\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScyk4HY8i531OwAVRnCrDP5vmClR2mWgsGA_YF2OVHvBlhENw\/viewform\" target=\"_blank\" rel=\"noopener\">Inscription<\/a><\/p>\n<p>Programme\u00a0 complet :<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervention du LISRA au colloque sur les recherches participatives avec des groupes d\u00e9viants, stigmatis\u00e9s, marginalis\u00e9s. quelles approches th\u00e9oriques, pratiques et d\u00e9ontologiques ? (1) Jeudi 13 septembre 2018 de 11h \u00e0 13h Centre de Formation Saint-Honor\u00e9 42-44 Rue de Romainville &#8211; 75019 Paris Notre laboratoire social travaille avec des r\u00e9cup\u00e9rateurs vendeurs de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[3],"tags":[32,104,61,73,77,105],"class_list":["post-2223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intervention","tag-developpement-social","tag-economie-populaire","tag-minorite","tag-precarite","tag-rapport-social","tag-recuperateurs-vendeurs-developpement-social"],"jetpack_featured_media_url":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2018\/07\/arton3822.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2QGRI-zR","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/2223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/comments?post=2223"}],"version-history":[{"count":5,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/2223\/revisions"}],"predecessor-version":[{"id":2229,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/2223\/revisions\/2229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media\/2224"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media?parent=2223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/categories?post=2223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/tags?post=2223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}