{"id":3926,"date":"2023-06-21T10:12:02","date_gmt":"2023-06-21T08:12:02","guid":{"rendered":"https:\/\/recherche-action.fr\/hugues-bazin\/?p=3926"},"modified":"2023-06-21T10:12:03","modified_gmt":"2023-06-21T08:12:03","slug":"des-tiers-espaces-aux-tiers-lieux-entre-contre-pouvoir-et-pouvoir-de-controle","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/hugues-bazin\/2023\/06\/21\/des-tiers-espaces-aux-tiers-lieux-entre-contre-pouvoir-et-pouvoir-de-controle\/","title":{"rendered":"Des tiers-espaces aux tiers-lieux, entre contre-pouvoir et pouvoir de contr\u00f4le"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il n&rsquo;y a pas de libre pens\u00e9e sans espaces lib\u00e9r\u00e9s, l&rsquo;occasion d&rsquo;intervenir sur la radio libre : <a href=\"https:\/\/nonmarchand.org\/grav\/entrez-sans-payer\/entrez-sans-payer-23-juin-2023-les-tiers-lieux-nouvel-outil-de-controle-social\" target=\"_blank\" rel=\"noreferrer noopener\">Radio Ballade<\/a> d\u00e9but juin 2023, autour des tiers espaces et des tiers lieux entre contre-pouvoir et pouvoir de contr\u00f4le, introduit par une pr\u00e9sentation tr\u00e8s critique de Benjamin Grassineau (<a href=\"https:\/\/labo.nonmarchand.org\/pmwiki\/Accueil\/Accueil\" target=\"_blank\" rel=\"noreferrer noopener\">sociologue des \u00e9changes non-marchands et ing\u00e9nierie des espaces de gratuit\u00e9<\/a>) suivie de mon interview.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2023\/06\/Entrez-sans-payer-23-juin-2023-Les-tiers-lieux-nouvel-.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Il n&rsquo;y a pas de libre pens\u00e9e sans espaces lib\u00e9r\u00e9s, l&rsquo;occasion d&rsquo;intervenir sur la radio libre : Radio Ballade d\u00e9but juin 2023, autour des tiers espaces et des tiers lieux entre contre-pouvoir et pouvoir de contr\u00f4le, introduit par une pr\u00e9sentation tr\u00e8s critique de Benjamin Grassineau (sociologue des \u00e9changes non-marchands et ing\u00e9nierie &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4],"tags":[53,87,90,91],"class_list":["post-3926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview","tag-innovation-sociale","tag-territoire","tag-tiers-espace","tag-tiers-lieux"],"jetpack_featured_media_url":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2023\/06\/Capture-decran-2023-06-21-093208.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2QGRI-11k","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/3926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":1,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"predecessor-version":[{"id":3929,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/3926\/revisions\/3929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media\/3927"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}