{"id":4783,"date":"2026-02-27T09:55:14","date_gmt":"2026-02-27T08:55:14","guid":{"rendered":"https:\/\/recherche-action.fr\/hugues-bazin\/?p=4783"},"modified":"2026-02-27T09:58:01","modified_gmt":"2026-02-27T08:58:01","slug":"la-ville-et-sa-peripherie","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/hugues-bazin\/2026\/02\/27\/la-ville-et-sa-peripherie\/","title":{"rendered":"La ville et sa p\u00e9riph\u00e9rie"},"content":{"rendered":"\n<p><strong>10e \u00e9dition |<\/strong> Manifestation du minist\u00e8re de la Culture organis\u00e9e par le Centre National du Livre<\/p>\n\n\n\n<p>\u00c0 l\u2019occasion de la 10e \u00e9dition des <em>Nuits de la lecture<\/em>, le CAUE du Gard a propos\u00e9 de croiser les regards d\u2019artistes et de professionnels autour de la vie dans les quartiers de grands ensembles, de leurs repr\u00e9sentations et de leurs relations avec la ville-centre, afin de mettre en lumi\u00e8re cr\u00e9ativit\u00e9, v\u00e9cus et dynamiques sociales.<\/p>\n\n\n\n<p>La soir\u00e9e a d\u00e9but\u00e9 avec l\u2019association <strong>Libr\u2019Air<\/strong>, qui a pr\u00e9sent\u00e9 une intervention autour de la cr\u00e9ativit\u00e9 des enfants du quartier Pissevin \u00e0 N\u00eemes. \u00c0 travers la lecture de leurs nouvelles, dont ils sont les auteurs, ou la diffusion d\u2019enregistrements audio, le public a \u00e9t\u00e9 plong\u00e9 dans une exp\u00e9rience immersive, renforc\u00e9e par la projection simultan\u00e9e de photographies.<\/p>\n\n\n\n<p>Puis, une performance de la troupe <strong>Stand\u2019hop<\/strong>, m\u00ealant danse hip-hop et rap, a \u00e9t\u00e9 propos\u00e9e. \u00c0 travers cette cr\u00e9ation artistique, les danseurs et rappeurs ont offert leurs regards sur la vie dans les grands ensembles, r\u00e9v\u00e9lant l\u2019\u00e9nergie, les solidarit\u00e9s, les tensions et l\u2019attachement aux lieux.<\/p>\n\n\n\n<p>Le chercheur <strong>Hugues Bazin<\/strong>, sp\u00e9cialiste de la recherche-action et des cultures urbaines, a pr\u00e9sent\u00e9 les r\u00e9sultats de ses travaux sur le lien entre hip-hop et quartiers populaires. Il a partag\u00e9 ses analyses sur le r\u00f4le du hip-hop comme espace d\u2019expression, de cr\u00e9ation et de repr\u00e9sentation sociale.<\/p>\n\n\n\n<p>Les interventions ont permis de m\u00ealer r\u00e9flexions et exp\u00e9riences personnelles, offrant au public un regard vivant et authentique sur la ville et sa p\u00e9riph\u00e9rie. La soir\u00e9e s\u2019est termin\u00e9e par un temps d\u2019\u00e9changes avec le public, afin de prolonger la discussion, poser des questions et partager impressions et ressentis.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/iRMmA8mVwDI?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>10e \u00e9dition | Manifestation du minist\u00e8re de la Culture organis\u00e9e par le Centre National du Livre \u00c0 l\u2019occasion de la 10e \u00e9dition des Nuits de la lecture, le CAUE du Gard a propos\u00e9 de croiser les regards d\u2019artistes et de professionnels autour de la vie dans les quartiers de grands ensembles, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4],"tags":[5,28,29,30,50,76,87,95],"class_list":["post-4783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview","tag-action-culturelle","tag-culture-populaire","tag-cultures-urbaines","tag-danse","tag-hip-hop","tag-rap","tag-territoire","tag-ville"],"jetpack_featured_media_url":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-27-094748-scaled-e1772182670851.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2QGRI-1f9","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/4783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/comments?post=4783"}],"version-history":[{"count":1,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/4783\/revisions"}],"predecessor-version":[{"id":4786,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/posts\/4783\/revisions\/4786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media\/4784"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/media?parent=4783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/categories?post=4783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/hugues-bazin\/wp-json\/wp\/v2\/tags?post=4783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}