{"id":1443,"date":"2013-04-02T19:10:29","date_gmt":"2013-04-02T18:10:29","guid":{"rendered":"http:\/\/recherche-action.fr\/intermedes\/?p=1443"},"modified":"2013-04-02T19:10:29","modified_gmt":"2013-04-02T18:10:29","slug":"1443","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/intermedes\/2013\/04\/02\/1443\/","title":{"rendered":"EXODUS"},"content":{"rendered":"<p><strong><span style=\"color: #0000ff\">Pour ceux d&rsquo;entre nous qui ont assist\u00e9 \u00e0 l&rsquo;expulsion des camps ou de l&rsquo;h\u00f4pital o\u00f9 les femmes et enfants Rroms avaient cherch\u00e9 refuge, nous avons vu &#8230;des images de l&rsquo;exode.<\/span><\/strong><\/p>\n<p><strong>Ce sont des images d&rsquo;un autre \u00e2ge , qui nous choquent et nous interpellent:<\/strong> attention l&rsquo;histoire balbutie , le racisme et l&rsquo;intol\u00e9rance reviennent et m\u00eame sur une tonalit\u00e9 respectable. Les banques ne peuvent elles pas en toute impunit\u00e9 refuser d&rsquo;ouvrir un compte aux Roumains (d&rsquo;origine Rom ou pas d&rsquo;ailleurs)? Nous\u00a0avons\u00a0beaucoup d&rsquo;exemples.<\/p>\n<p><span style=\"color: #ff0000\">L&rsquo;exode est une violence inimaginable inflig\u00e9e \u00e0 des hommes, des femmes et des enfants qui perdent tout et\u00a0surtout\u00a0leur \u00e9nergie de vivre et de r\u00e9agir. \u00a0\u00a0Mais c&rsquo;est \u00a0aussi une opportunit\u00e9 de faire taire la demande, de faire taire le scandale<\/span>. Tous ceux qui sont partis d&rsquo;eux m\u00eames semblent ne plus avoir de besoins; ils ne sont plus l\u00e0 pour dire qu&rsquo;ils existent. \u00a0La trag\u00e9die n&rsquo;existe plus quand les acteurs sont invisibles,\u00a0<em><strong>invisibilis\u00e9s.<\/strong><\/em><\/p>\n<p>L&rsquo;exode ce sont donc ici, ces s\u00e9dentaires expuls\u00e9s, car ils voulaient\u00a0trouver racine et \u00e0 qui on jette une image de nomades.<\/p>\n<p>Mais ce sont aussi nous tous, enfants, \u00a0familles, adultes isol\u00e9s des quartiers, des\u00a0milieux\u00a0populaires &#8230; qui\u00a0disparaissent\u00a0des statistiques, des listes, qui ne demandent plus , n&rsquo;attendent plus (ce qui au demeurant n&#8217;emp\u00eache pas de conna\u00eetre l\u00e0 aussi fr\u00e9quemment de nombreuses expulsions locatives).<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170630.jpg\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"IMG_20130330_170630\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170630-300x224.jpg\" width=\"273\" height=\"216\" \/><\/a><\/p>\n<p>Que peut on\u00a0faire\u00a0face \u00e0 l&rsquo;exode? \u00a0Garder la m\u00e9moire, recueillir les r\u00e9cits, les traces, les t\u00e9moignages.\u00a0ainsi \u00e0 Robinson, et \u00e0 Animakt et avec tous nos amis, nous allons recueillir paroles d&rsquo;enfants, images , \u00a0r\u00e9cits, impressions et dessins pour dire au\u00a0travers\u00a0d&rsquo;un \u00e9v\u00e9nement \u00e0 cr\u00e9er, que quelque chose s&rsquo;est pass\u00e9 , que quelque chose a \u00e9t\u00e9 cr\u00e9\u00e9 , que nous avons v\u00e9cu une v\u00e9ritable aventure sociale qui produira des effets.<\/p>\n<p><span style=\"color: #ff0000\"><strong>Face \u00e0 l&rsquo;exode, nous ferons Diaspora<\/strong>\u00a0,<\/span> et autour de Robinson, tout un r\u00e9seau se cr\u00e9e . ce sont les anciens qui reviennent si souvent, qui se retrouvent, qui se rassemblent au moindre besoin. Ce sont ces amis qui se rapprochent , ces liens qui se transmettent de personne \u00e0 personne, ces histoires dont on garde le fil.<\/p>\n<p><em><strong>Mais l&rsquo;exode n&rsquo;est pas que du n\u00e9gatif, c&rsquo;est aussi ce que l&rsquo;on cr\u00e9e face \u00e0 l&rsquo;insupportable. \u00a0C&rsquo;est une recherche d&rsquo;autonomie salvatrice, une recherche de\u00a0quelque\u00a0chose de fiable, d&rsquo;une parole vraie, d&rsquo;une autorit\u00e9 qui ne mente pas,<\/strong><\/em> d&rsquo;une responsabilit\u00e9 qui s&rsquo;assume. \u00a0Nous allons, entre nous mettre en oeuvre un travail social fiable.<\/p>\n<p><b><i>\u00ab\u00a0L\u2019exode ne\u00a0 signifie pas n\u00e9cessairement partir ailleurs, ce sont toutes les formes du \u00ab processus\u00a0 de soustraction \u00e0 la relation avec le capital par l\u2019actualisation de l\u2019autonomie\u00a0 potentielle de la force de travail. L\u2019exode prend des figures infinies, (&#8230;) , toutes \u00ab pr\u00e9figurations\u00a0 concr\u00e8tes d\u2019un pouvoir alternatif \u00bb (Hardt)\u00a0<\/i><\/b><\/p>\n<p><strong>Lundi : \u00a0 Chantier \u00e0 Buno<\/strong><\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/LundBun.jpg\"><img decoding=\"async\" alt=\"LundBun\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/LundBun-300x225.jpg\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Ce lundi, profitant du soleil et d&rsquo;une raltive hausse de stemp\u00e9ratures, notre petite \u00e9quipe a commenc\u00e9 la dalle en ciment du Chalet des Robinsons, prochainement \u00e0 ouvrir dans le parc du ch\u00e2teau de Buno<\/p>\n<p><strong>Samedi et dimanche: Week end ados et abeilles et dimanche terrain<\/strong><\/p>\n<p>Kroniks du groupe abeille:<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/AffCsi.jpg\"><img decoding=\"async\" alt=\"AffCsi\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/AffCsi-300x224.jpg\" width=\"300\" height=\"224\" \/><\/a><\/p>\n<p>Samedi\u00a0:<\/p>\n<p>Le CENTRE SOCIAL DE CHILLY de Chilly est toujours aussi accueillant, pour notre public DE LONGJUMEAU, alors que l\u2019hiver tarde \u00e0 plier flocons.<\/p>\n<p>D\u00e8s notre arriv\u00e9e, une \u00e9quipe se met en cuisine, pendant que d \u2018autres s\u2019essayent \u00e0 une d\u00e9licate manipulation apicole\u00a0: le cirage des cadres, qui accueilleront miel et abeilles. \u00a0On termine aussi les affiches linograv\u00e9es qui annoncent le prochain atelier de cuisine de rue massive. Apr\u00e8s manger, Benjamin, qui habitait le camp de moulin-galant, nous raconte l\u2019expulsion qui a eu lieu la veille. Puis on discute du voyage qui aura lieu cet \u00e9t\u00e9.<\/p>\n<p>On finit l\u2019apr\u00e8s-midi en allant encourager Dylan et Luis, en pleine r\u00e9p\u00e9tition de leur groupe \u00ab\u00a0Wolf Illusion\u00a0\u00bb.<\/p>\n<p>Dimanche\u00a0:<\/p>\n<p>C\u2019est avec tristesse que nous d\u00e9couvrons la mort de nos ruches, sans doute affam\u00e9es par un hiver trop tardif.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/RuchOuv.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"RuchOuv\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/RuchOuv-300x224.jpg\" width=\"300\" height=\"224\" \/><\/a><\/p>\n<p>Mais nous sommes 18 ce dimanche, et une fois nos abeilles rituellement incin\u00e9r\u00e9es, et les ruches purifi\u00e9es au chalumeau, le pique-nique autour du feu a plus des allures de f\u00eate que de deuil.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/CadrAb.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"CadrAb\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/03\/CadrAb-224x300.jpg\" width=\"224\" height=\"300\" \/><\/a><\/p>\n<p>Il se termine par une chasse \u00e0 l\u2019\u0153uf sauvage, pr\u00e9par\u00e9e par les plus grands.<\/p>\n<p>On d\u00e9broussaille aussi les fruitiers, et on \u00a0s\u00e8me des m\u00e9langes de fleurs, qui serviront de garde manger aux nouveaux essaims d\u2019abeilles qu\u2019on accueillera au printemps.<\/p>\n<p><strong><span style=\"text-decoration: underline\">SAMEDI\u00a0:<\/span><\/strong><\/p>\n<p><strong>La Villa St Martin\u00a0:<\/strong><\/p>\n<p>A la villa St Martin, le vent souffle.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020730.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1451 alignleft\" alt=\"P1020730\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020730-300x224.jpg\" width=\"238\" height=\"180\" \/><\/a>Pour autant les enfants sont nombreux \u00e0 particip\u00e9 aux diff\u00e9rents ateliers propos\u00e9. Le jeu du \u00ab\u00a0devine t\u00eate\u00a0\u00bb fait son effet tout comme le jeu du \u00ab\u00a0tic tac boum\u00a0\u00bb.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020668.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1449 alignleft\" alt=\"P1020668\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020668-300x224.jpg\" width=\"209\" height=\"158\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Cot\u00e9 cuisine,\u00a0 ramona et maria avec un groupe d\u2019enfant nous pr\u00e9parent un g\u00e2teau au chocolat digne de ce nom. Pr\u00e8s de l\u2019atelier, s\u2019improvise un petit match de football avec Madalin. Aujourd\u2019hui le coin petit enfance a \u00e9t\u00e9 peu investi, en revanche la caisse comportant du sable, des sceaux et des pelles a suscit\u00e9 l\u2019enthousiasme des petit comme des plus grands au point qu\u2019\u00e0 la fin de l\u2019atelier, la caisse soit presque vide. Le conseil de quartier \u00e0 mis du temps \u00e0 d\u00e9marrer, mais au final les enfants \u00e9tait nombreux. Apr\u00e8s que le plus gros du mat\u00e9riel soit rang\u00e9, nous avons go\u00fbter, nous nous sommes r\u00e9gal\u00e9s.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020787.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1452 alignleft\" alt=\"P1020787\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020787-300x224.jpg\" width=\"223\" height=\"169\" \/><\/a><\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020710.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1450 alignleft\" alt=\"P1020710\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020710-300x224.jpg\" width=\"222\" height=\"174\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Batucada\u00a0!\u00a0 <\/strong><\/p>\n<p><strong>C\u2019\u00e9tait la derni\u00e8re s\u00e9ance de Batucada avant le carnaval et les enfants sont arriv\u00e9s bien motiv\u00e9s<\/strong>, ils ont courus jusqu\u2019\u00e0 la porte et pareil pour aller chercher les instruments. Les r\u00e9p\u00e9titions ont commenc\u00e9 de suite, en cercle pour commencer, certains ont utilis\u00e9s plusieurs instruments. Ensuite nous avons march\u00e9 dans la salle pour simuler le carnaval.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_153844.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"IMG_20130330_153844\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_153844-224x300.jpg\" width=\"153\" height=\"199\" \/><\/a><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_1521361.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"IMG_20130330_152136\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_1521361-300x224.jpg\" width=\"231\" height=\"184\" \/><\/a><\/p>\n<p>Pour finir, nous sommes all\u00e9s \u00e0 l\u2019ext\u00e9rieur pour se mettre dans les conditions et au loin, nous pouvions observer des joueurs de football danser au rythme de la musique, nous avons fait le tour du centre de loisir, en passant par les jeux, et avons termin\u00e9 ce petit parcours dans la salle avec les applaudissements de la responsable du club ados et son coll\u00e8gue.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170630.jpg\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"IMG_20130330_170630\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170630-300x224.jpg\" width=\"273\" height=\"216\" \/><\/a><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170719.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"IMG_20130330_170719\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130330_170719-300x224.jpg\" width=\"229\" height=\"183\" \/><\/a><\/p>\n<p><strong><span style=\"text-decoration: underline\">VENDREDI:<\/span><\/strong><\/p>\n<p><b>Au jardin de Chilly\u00a0:<\/b><\/p>\n<p><strong><span style=\"color: #0000ff\">Pour nous les Robinsons ce fut le dernier jour de pr\u00e8s de 4 ann\u00e9es de jardinage au potager de Chilly-Mazarin.<\/span><\/strong><\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020656.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1454 alignleft\" alt=\"P1020656\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020656-300x224.jpg\" width=\"164\" height=\"124\" \/><\/a> <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020661.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1455 alignleft\" alt=\"P1020661\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020661-300x224.jpg\" width=\"201\" height=\"152\" \/><\/a> <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020663.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1456 alignleft\" alt=\"P1020663\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020663-300x224.jpg\" width=\"176\" height=\"133\" \/><\/a><\/p>\n<p>Nous chargeons la cabane dans le camion que nous am\u00e8nerons au verger. Nous r\u00e9cup\u00e9rons quelques plantes notamment de la rhubarbe et de la m\u00e9lisse qui auront le droit \u00e0 une nouvelle terre, <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020653.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1453 alignleft\" alt=\"P1020653\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020653-300x224.jpg\" width=\"206\" height=\"156\" \/><\/a>celle de Saulx.<\/p>\n<p>La mairie nous a laiss\u00e9 du BRF que nous utilisons pour pailler les massifs avec l\u2019aide du groupe de la r\u00e9sidence soleil. Nous nous promettons de nous revoir, le groupe de la r\u00e9sidence viendra nous rendre visite et nous pr\u00eater main forte au terrain de l\u2019\u00e9querre.<\/p>\n<p>Nous terminons l\u2019apr\u00e8s-midi par un saut au verger pour y d\u00e9poser le cabanon et c\u2019est l\u2019occasion pour certains de d\u00e9couvrir ce terrain sur lequel nous continuons nos activit\u00e9s certains samedi.<\/p>\n<p><strong>La Rocade:<\/strong><\/p>\n<p>Ni trop froid, ni trop chaud, un temps parfait cette apr\u00e8s midi \u00e0 la rocade pour commencer les petits plat de la soir\u00e9e conviviale avec la cuisine du DAEV. Une tarte au fromage et une autre \u00e0 la dinde puis un g\u00e2teau au chocolat. Malgr\u00e9 quelques accidents de d\u00e9part, plus de poignet \u00e0 po\u00eale, une p\u00e2te sabl\u00e9e \u00e0 la place d&rsquo;une sal\u00e9e, le gaz qui ne sort pas et plus d&rsquo;eau pour l&rsquo;\u00e9vier, mais tout \u00e0 fini par s&rsquo;arranger et un tr\u00e8s g\u00e9n\u00e9reux monsieur nous offert de l&rsquo;eau chez lui.<\/p>\n<p>Des mamans et des jeunes nous ont bien aid\u00e9s, le poste de musique \u00e0 nos c\u00f4t\u00e9, ce fut un bon moment de partage dans une ambiance musicale bien festif. <span style=\"color: #0000ff\"><strong>C&rsquo;est \u00e7a l&rsquo;esprit communautaire, c&rsquo;est \u00e7a l&rsquo;esprit Robinson\u00a0!<\/strong><\/span><\/p>\n<p>Pendant ce temps, des tout petits jouets \u00e0 la dinette, aux poup\u00e9es, des jeux d\u2019assemblages, et touchaient des livres de mati\u00e8res diff\u00e9rentes. Mais attention, ils ne faux pas emb\u00eater les autres et partager les jouets.<\/p>\n<p>Les grands \u00e9taient dans la tente jeux de soci\u00e9t\u00e9 avec Aline, et se sont beaucoup amuser avec le \u00ab\u00a0Tic-Tac BOUM\u00a0!\u00a0\u00bb un \u00a0jeu o\u00f9 il faut trouver des mots avec des syllabes avant que la bombe n\u2019explose, <strong>un bon jeu pour apprendre et enrichir sont vocabulaire tout en s\u2019amusant.<\/strong> Tout les ados y sont pass\u00e9s, la tente \u00e9tait bien remplie.<\/p>\n<p>Le bac \u00e0 sable et les instruments de musique ont \u00e9t\u00e9 bien investis \u00e9galement, chaque enfant \u00e0 essay\u00e9 plusieurs instrument pour en exploiter les diff\u00e9rents sons, et apr\u00e8s avoir choisi leur pr\u00e9f\u00e9r\u00e9, nous avons d\u00e9fil\u00e9 en faisant le tour de la b\u00e2che une fois, deux fois puis trois fois avant d\u2019aller vers les tentes, puis la cuisine, les toboggans et enfin les mamans. <strong><span style=\"color: #000000\">Les enfants voulaient qu\u2019on les entende et se fut choses faite.<\/span><\/strong><\/p>\n<p>L\u2019atelier s\u2019est termin\u00e9 avec tous les enfants dansant sur de la musique accompagn\u00e9 de Ramona, on pouvait croire \u00e0 un mini festival ext\u00e9rieur, les enfants se sont beaucoup amus\u00e9s, mais malheureusement il est temps de ranger.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"text-decoration: underline\">JEUDI:<\/span><\/strong><\/p>\n<p><b>Wissous\u00a0:<\/b><\/p>\n<p>A notre arriv\u00e9s ce matin \u00e0 Wissous, il y a eu quelques flocons de neige, mais pas d\u2019inqui\u00e9tude, \u00e7a n\u2019a pas dur\u00e9 longtemps.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3169.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1457 alignleft\" alt=\"IMG_3169\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3169-300x224.jpg\" width=\"245\" height=\"185\" \/><\/a>Les enfants sont arriv\u00e9s petits \u00e0 petits, les premiers nous aident \u00e0 installer, pendant que Ramona va chercher d\u2019autres enfants sur le camp. En un rien de temps les ateliers ont commenc\u00e9s, la petite poup\u00e9e est au petit soin,\u00a0 les enfants la nourrisse avec la dinette, puis la prom\u00e8ne avec la poussette.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_31921.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1462 alignleft\" alt=\"IMG_3192\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_31921-224x300.jpg\" width=\"169\" height=\"223\" \/><\/a>Ensuite les enfants sont nombreux \u00e0 aller sur les petites tables pour dessiner, colori\u00e9, faire des exercices pour faire de beaux ronds, apprendre \u00e0 compter et \u00e0 \u00e9crire leurs pr\u00e9noms.<strong> Les plus grands s\u2019installent sur la grande table pour faire des exercices d\u2019\u00e9crire, elles sont bien concentr\u00e9s et recopient les textes des livres avec pr\u00e9cision.<\/strong>\u00a0<a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3216.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1461 alignright\" alt=\"IMG_3216\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3216-300x224.jpg\" width=\"181\" height=\"138\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3180.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1458 alignleft\" alt=\"IMG_3180\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3180-300x224.jpg\" width=\"203\" height=\"155\" \/><\/a>Un petit groupe nous font une d\u00e9monstration de cirque avec un pyramide humaine tr\u00e8s r\u00e9ussit.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1460 alignleft\" alt=\"IMG_3200\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3200-300x224.jpg\" width=\"221\" height=\"167\" \/><\/a>Les enfants jouent aussi avec la dinette, ils font de la cuisine et se concentrent sur les \u0153ufs, les balancent sur les po\u00eales, mais attention, il ne faut pas les faire tomber.<\/p>\n<p>Le rangement a \u00e9t\u00e9 tr\u00e8s efficace, les enfants \u00e9taient bien motiv\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Jardin de Saulx\u00a0:<\/strong><\/p>\n<p>Le froid s\u2019est install\u00e9 en cette fin de semaine \u00e0 Saulx. Nous aurons m\u00eame le droit \u00e0 quelques flocons de neige, du jamais vu pour une fin mars\u00a0!<\/p>\n<p>Cela ne durera pas et nous avons amen\u00e9 avec nous la motobineuse. Nous continuons donc de retourner les parcelles en attendant que le temps et la terre se r\u00e9chauffe pour pouvoir y effectuer des semis.<\/p>\n<p>Jean-Jacques a r\u00e9cup\u00e9r\u00e9 des tiges de bambous et nous tentons de les faire prendre racine en les plongeant dans un grand bac d\u2019eau. Aussi un groupe se charge de r\u00e9cup\u00e9rer du bois en quantit\u00e9 et l\u2019autre groupe le d\u00e9bite en b\u00fbches. <strong>Nous ne manquerons pas de bois pour cette ann\u00e9e\u00a0!<\/strong> De plus cela nous permet de nous r\u00e9chauffer malgr\u00e9 un vent frais.<\/p>\n<p><strong>Le gouter est pris dans la bonne humeur malgr\u00e9 l\u2019annonce de l\u2019expulsion du camp de Moulin-galant qui touche et qui interpelle chaque participant aujourd\u2019hui.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Skatepark\u00a0<\/strong><b>: <\/b><\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3223.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1466 alignleft\" alt=\"IMG_3223\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3223-300x224.jpg\" width=\"255\" height=\"194\" \/><\/a>Malgr\u00e9 un vent glacial, l\u2019atelier d\u2019aujourd\u2019hui c\u2019est d\u00e9roul\u00e9 dans la joie et la bonne humeur\u00a0! Un petit groupe accompagn\u00e9 de Garance a longuement feuillet\u00e9 des livres dont \u00ab\u00a0Pokko et la rivi\u00e8re aux crocodiles\u00a0\u00bb et \u00ab\u00a0la petite sir\u00e8ne\u00a0\u00bb.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3241.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1469 alignleft\" alt=\"IMG_3241\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3241-300x224.jpg\" width=\"225\" height=\"171\" \/><\/a><\/p>\n<p>Pendant ce temps les plus petits se sont amus\u00e9s avec la dinette et les poup\u00e9es.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3224.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1467 alignleft\" alt=\"IMG_3224\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3224-300x224.jpg\" width=\"164\" height=\"124\" \/><\/a>D\u2019autres ont fait des jeux de soci\u00e9t\u00e9 le \u00ab\u00a0pic pirate\u00a0\u00bb avec Ramona, le jeu de voiture \u00ab\u00a0pitch car mini\u00a0\u00bb avec Pierre, le \u00ab\u00a0Halli Galli\u00a0\u00bb \u00e9galement, il y a aussi eu du coloriage \u00e0 la pastel. Beaucoup de maman \u00e9taient pr\u00e9sente aussi, et Jean Jacques est pass\u00e9 nous dire bonjour. Les enfants semblent s\u2019\u00eatre bien amus\u00e9s, tout le monde \u00e0 particip\u00e9 au rangement, puis nous avons pris le go\u00fbt\u00e9 bien au calme, bient\u00f4t nous auront plus assez de verres.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Croix-Breton\u00a0: <\/strong><\/p>\n<p><strong>Nous sommes de plus en plus nombreux \u00e0 la croix breton\u00a0!!<\/strong> Aujourd\u2019hui nous avons rendez vous avec le soleil, et c\u2019est plus de 10 enfants qui nous retrouvent sur l\u2019atelier. Nous organisons avec\u00a0 les enfants un grand jeu collectif du b\u00e9ret, et c\u2019est avec plaisir que petit et grand se rassemble autour de cette activit\u00e9 qui durera tout l\u2019atelier tellement nous nous sommes amus\u00e9s\u00a0!<\/p>\n<p>Il est d\u00e9j\u00e0 l\u2019heure de prendre le go\u00fbter. Ayoub et Yasmin\u00a0 s\u2019occupent de le distribuer pendant que nous chantons assis tous ensemble. Il est maintenant l\u2019heure de se dire au revoir, et de se donner rendez-vous la semaine prochaine pour un nouvel \u00e9pisode des Robinsons\u00a0!<\/p>\n<p><strong><span style=\"text-decoration: underline\">MERCREDI:<\/span><\/strong><\/p>\n<p><b>Moulin Galant\u00a0: <\/b><\/p>\n<p><strong><span style=\"color: #ff0000\">Ce mercredi est un jour sp\u00e9cial. C\u2019est le c\u0153ur gros que nous partons faire notre dernier atelier \u00e0 Moulin galant. L\u2019expulsion est finalement confirm\u00e9e pour demain, jeudi 28 mars 2013.<\/span><\/strong><\/p>\n<p><strong>Hier, nous pensions encore essayer de faire l\u2019atelier dans l\u2019h\u00f4pital o\u00f9 s&rsquo;\u00e9taient r\u00e9fugi\u00e9es, \u00a024h \u00a0les familles roms dans l&rsquo;id\u00e9e \u00a0trouver un endroit digne pour habiter. Nous avons finalement quitt\u00e9\u00a0 les lieux mardi\u00a0 soir, et aujourd\u2019hui, nous sommes de retour sur le camp avec du renfort pour cet ultime atelier avec nos petits rom\u2019binsons.\u00a0 Ils sont nombreux \u00e0 venir nous voir et leurs parents aussi. La tension est palpable, les familles pr\u00e9parent leur d\u00e9part, <span style=\"color: #0000ff\">les questions fusent sur l\u2019expulsion, toujours les m\u00eames\u00a0: \u00ab\u00a0comment \u00e7a va se passer demain, o\u00f9 va &#8211; t\u2019on aller\u00a0?\u00a0\u00bb<\/span><\/strong><\/p>\n<p>Mais, malgr\u00e9 tout, et avec l\u2019aide de nos coll\u00e8gues d\u2019Animakt, nous avons pu \u00e0 la fois, passer un peu de temps avec les adultes pour les apaiser et jouer avec les enfants. <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020587.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1470 alignleft\" alt=\"P1020587\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020587-300x225.jpg\" width=\"244\" height=\"185\" \/><\/a>Sandrine et sa fille, Naomie et Delphine d\u2019Animakt sont venus avec des crayons de toutes les couleurs, des feuilles, un petit jeu de cochons qu\u2019on jette pour gagner des points selon la mani\u00e8re dont ils tombent.<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1473 alignleft\" alt=\"P1020600\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020600-300x224.jpg\" width=\"251\" height=\"190\" \/><\/a><\/p>\n<p><strong>Abdel, ami et ancien permanent de l\u2019association est venu de Lille et propose a<\/strong><strong>ux enfants d\u2019apprendre \u00e0 faire un feu en toute s\u00e9curit\u00e9.<\/strong><\/p>\n<p>Delphine lit un livre aux petits, tandis que <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P10205881.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1475 alignright\" alt=\"P1020588\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P10205881-224x300.jpg\" width=\"146\" height=\"192\" \/><\/a>Garance \u00e9coute Izabela lui en lire un autre. Souad, Aline et Ramona discutent avec les parents et gravitent autour de l\u2019atelier, distribuant des bisous. Autour de nous, les caravanes se d\u00e9pouillent de leur contenu qu\u2019on emballe pour le d\u00e9part de demain matin.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020592.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1472 alignleft\" alt=\"P1020592\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020592-300x224.jpg\" width=\"238\" height=\"180\" \/><\/a><\/p>\n<p><a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020604.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1474 alignleft\" alt=\"P1020604\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/P1020604-300x224.jpg\" width=\"230\" height=\"174\" \/><\/a><\/p>\n<p>Certaines caravanes ont \u00e9t\u00e9 d\u00e9truites par les familles, elles m\u00eames, en partant pour l\u2019h\u00f4pital, et quelques enfants s\u2019amusent \u00e0 poursuivre la d\u00e9molition. Nous nous rassemblons pour prendre notre go\u00fbter tous ensemble. Sandrine et Naomie ont apport\u00e9 des pains au chocolat et des fruits que nous mangeons en plus du reste. Nous prenons quelques minutes pour dire aux enfants que c\u2019est notre dernier atelier tous ensemble mais que tant que nous pourrons les suivre, nous continuerons \u00e0 faire des choses avec eux et pour eux,\u00a0 et que ce sont des supers loulous\u00a0!!!!!!<\/p>\n<p>Nous aurons \u00e9norm\u00e9ment de mal \u00e0 quitter le camp\u00a0; nous distribuons plein de \u00ab\u00a0poupiks\u00a0\u00bb. BISOUUUUUUS\u00a0!!!<\/p>\n<p><strong>Jardin de Saulx\u00a0:<\/strong><\/p>\n<p>Le froid est de retour cette semaine et on ne sait pas si nous sommes vraiment rentr\u00e9s dans cette p\u00e9riode qui se nomme \u00ab\u00a0le printemps\u00a0\u00bb. D\u00e9cid\u00e9ment l\u2019hiver aura \u00e9t\u00e9 tr\u00e8s long\u2026<\/p>\n<p>Qu\u2019importe nous arrosons nos derniers semis et plantations (laurier, lavande, persil, f\u00e8ves\u2026). Un petit groupe <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3163.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" alt=\"IMG_3163\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3163-300x224.jpg\" width=\"206\" height=\"156\" \/><\/a>part chercher du bois et en ram\u00e8ne en quantit\u00e9\u00a0! Nous dispo<a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3153.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"IMG_3153\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3153-300x224.jpg\" width=\"213\" height=\"163\" \/><\/a>sons du BRF autour de quelques fleurs et de plans de fraisiers. Nous continuons de nettoyer le terrain dans ses moindres recoins.<a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3155.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" alt=\"IMG_3155\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_3155-300x224.jpg\" width=\"185\" height=\"142\" \/><\/a><\/p>\n<p>Zora surveille assidument les fleurs qui poussent aux 4 coins du jardin, en particulier les bulbes qui sortent de terre.<\/p>\n<p>Finalement nous faisons abstraction du froid pour une belle apr\u00e8s-midi pass\u00e9e \u00e0 l\u2019\u00e9querre.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ludoth\u00e8que\/parc Nativelle\u00a0:\u00a0 <\/strong><\/p>\n<p>Aujourd\u2019hui nous \u00e9tions\u00a0 un petit groupe \u00e0 partir au Parc Nativelle sous la douceur de ce mois de Mars.<a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_155634.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1480 alignright\" alt=\"IMG_20130327_155634\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_155634-300x224.jpg\" width=\"210\" height=\"160\" \/><\/a><\/p>\n<p>Les enfants \u00e9taient pleins d\u2019\u00e9nergie et nous avons tout de suite commenc\u00e9 par une chor\u00e9graphie sur la chanson du c\u00e9l\u00e8bre chanteur cor\u00e9en \u00ab Psy\u00a0\u00bb. Le groupe c\u2019est s\u00e9par\u00e9 en deux petits groupes.<\/p>\n<p>Un\u00a0 groupe a fait des jeux comme \u00ab\u00a0Chat famille\u00a0\u00bb. Et un\u00a0 autre groupe c\u2019est embarquer dans une histoire d\u2019\u00e9quipage qui emmenait des <a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_154456.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1479 alignleft\" alt=\"IMG_20130327_154456\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_154456-300x224.jpg\" width=\"222\" height=\"169\" \/><\/a>voyageurs \u00e0 New-York avec \u00a0plein de p\u00e9rip\u00e9ties en chemin. Cette apr\u00e8s midi c\u2019est fini par un gouter dans l\u2019enthousiasme des enfants qui \u00e0 marqu\u00e9 ce mercredi.<a href=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_155949.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1481 alignleft\" alt=\"IMG_20130327_155949\" src=\"http:\/\/recherche-action.fr\/intermedes\/files\/2013\/04\/IMG_20130327_155949-300x224.jpg\" width=\"167\" height=\"126\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>KroniKs des Robinsons de Grenoble<\/strong><\/span><\/p>\n<p>De nouvelles familles se joignent \u00e0 nous pour jardiner. Les enfants et les m\u00e8res disposent du BRF sur toutes les all\u00e9es tout en fessant connaissance.<br \/>\nNotre jardin commence \u00e0 vraiment \u00eatre beau.\u00a0 Des mamans viennent \u00e0 l&rsquo;atelier gr\u00e2ce aux affichent que nous disposons dans le quartier. Enrick (jardinier) a dispos\u00e9 une grande banderole pour que notre jardin soit r\u00e9p\u00e8rer par tout le monde.<br \/>\nQuelques enfants s&rsquo;installent sur nos nattes et s&#8217;emparent des jeux .<br \/>\nLa pluie pointe son nez pour le gouter, nous allons nous mettre \u00e0 l\u2019abri sous le patio.<br \/>\nUne maman nous offre des loukoums, du caf\u00e9 et des g\u00e2teaux.\u00a0 Nous projetons pour le prochain rendez-vous de confectionner des p\u00e2tisseries.<\/p>\n<p><strong><span style=\"color: #0000ff\">Des nouvelles des ateliers de DIE<\/span><\/strong><\/p>\n<p>Les ateliers de rue de Die poursuivent leur bout de chemin gr\u00e2ce \u00e0 l&rsquo;aide des habitants. La correspondance\u00a0 entre les enfants se maintient et nous en sommes tous ravies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour ceux d&rsquo;entre nous qui ont assist\u00e9 \u00e0 l&rsquo;expulsion des camps ou de l&rsquo;h\u00f4pital o\u00f9 les femmes et enfants Rroms avaient cherch\u00e9 refuge, nous avons vu &#8230;des images de l&rsquo;exode. Ce sont des images d&rsquo;un autre \u00e2ge , qui nous choquent et nous interpellent: attention l&rsquo;histoire balbutie , le racisme et l&rsquo;intol\u00e9rance reviennent et m\u00eame &hellip; <a href=\"https:\/\/recherche-action.fr\/intermedes\/2013\/04\/02\/1443\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;EXODUS&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":0,"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/intermedes\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}