{"id":472,"date":"2014-11-11T00:47:00","date_gmt":"2014-11-10T23:47:00","guid":{"rendered":"http:\/\/recherche-action.fr\/labo-social\/?p=472"},"modified":"2016-05-11T17:53:26","modified_gmt":"2016-05-11T15:53:26","slug":"labos-sociaux-des-espaces-critiques-au-coeur-de-la-societe","status":"publish","type":"post","link":"https:\/\/recherche-action.fr\/labo-social\/2014\/11\/11\/labos-sociaux-des-espaces-critiques-au-coeur-de-la-societe\/","title":{"rendered":"Labos sociaux : des espaces critiques au c\u0153ur de la soci\u00e9t\u00e9"},"content":{"rendered":"<p>Nous repla\u00e7ons les labos en recherche-action dans l\u2019enjeu social et scientifique contemporain comme n\u00e9cessit\u00e9 d\u2019ouvrir des espaces critiques et instituant \u00e0 partir de l\u2019exp\u00e9rimentation sociale. Autrement dit, il s\u2019agit de rappeler l\u2019urgence de relier mouvement d\u2019une recherche contestatrice et luttes sociales \u00e9mergentes sur de nouveaux mod\u00e8les de pens\u00e9e, d\u2019organisation et de gouvernance. Ce textes est le fruit d\u2019un espace collaboratif, partie \u00e9merg\u00e9e d\u2019une intelligence sociale qui peut prendre des formes multiples sans en exclure les aspects rugueux, imparfaits, t\u00e2tonnant, elliptique, voire contradictoires. Cette tension est le propre d\u2019une communaut\u00e9 d\u2019acteurs-chercheurs dont la vivacit\u00e9 ne se mesure pas au nombre de \u00ab\u00a0projets\u00a0\u00bb, mais au jeu de correspondances in\u00e9dites entre des espaces concrets d\u2019implication et des espaces r\u00e9flexifs. C\u2019est ce qui d\u00e9termine notre capacit\u00e9 innovatrice et notre pertinence en sciences sociales, mais aussi nous s\u00e9pare des mod\u00e8les \u00e9tablis de la production de la connaissance et de la pens\u00e9e politique. Face \u00e0 la violence sociale et symbolique qui nous impose souvent des conditions de vie pr\u00e9caire, nous opposons imp\u00e9rativement des \u00ab\u00a0Zones Autonomes \u00e0 D\u00e9fendre\u00a0\u00bb de l\u2019exp\u00e9rience humaine et de la pens\u00e9e.<\/p>\n<h2>Provoquer des espaces cr\u00e9atifs et autonomes d\u2019une pens\u00e9e h\u00e9t\u00e9rodoxe comme nouveaux lieux de la critique sociale<\/h2>\n<p>Le processus de sectorisation, de sp\u00e9cialisation et de corporatisme autant du milieu de la recherche que celui de l\u2019action sociale et culturelle conduit \u00e0 la fois \u00e0 une pr\u00e9carisation de ses auteurs et une destruction de la vie intellectuelle achev\u00e9e par le conformisme qu\u2019installent les logiques de pouvoir acad\u00e9miques ou n\u00e9olib\u00e9rales. Cela se traduit notamment par la f\u00e9tichisassions des dispositifs comme les appels \u00e0 projets pour les programmes ou \u00e0 contributions pour les colloques et les publications qui, sous le couvert de m\u00e9thodes pr\u00e9tendument rationnelles et scientifiques verrouillent la production de connaissance et nient l\u2019intelligence sociale dont elle est issue. Que les sciences humaines et sociales, sens\u00e9es devoir contribuer prioritairement \u00e0 la connaissance des r\u00e9alit\u00e9s actuelles soient quasiment absentes ou inaudibles dans les d\u00e9bats et les d\u00e9cisions des politiques publiques prouve le peu de consid\u00e9ration dont b\u00e9n\u00e9ficie le syst\u00e8me de production actuel de savoirs parcellaris\u00e9s. L&rsquo;humain subit ainsi une double r\u00e9ification\u00a0: il peut \u00eatre r\u00e9duit \u00e0 une donn\u00e9e d\u2019ajustement \u00e9conomique dont seuls les lobbies tirent profit\u00a0; il se trouve fig\u00e9 dans une appartenance identitaire essentialiste (Roms, immigr\u00e9s, ch\u00f4meurs, etc.), qui justifie toutes les discriminations.<\/p>\n<p>Cette atrophie de la pens\u00e9e emp\u00eache de nommer les formes \u00e9mergentes de lutte et d\u2019innovation, multiples, mais bien r\u00e9elles tout en vidant les notions et concepts de leur port\u00e9e critique, critique sociale pourtant indispensable et ins\u00e9parable de la structuration des individus et d\u2019une transformation de la soci\u00e9t\u00e9. L\u2019\u00e9criture de soi et d\u2019un r\u00e9cit collectif, la r\u00e9flexivit\u00e9, la praxis, la formation action, la recherche-action participent de ces processus qu\u2019il est urgent pour chacun de se r\u00e9approprier.<\/p>\n<p>Effectivement, si les structures traditionnelles de la recherche et les \u00ab\u00a0corps interm\u00e9diaires\u00a0\u00bb de l\u2019action, ne peuvent plus jouer ce r\u00f4le, Il appartient \u00e0 une g\u00e9n\u00e9ration d\u2019\u00ab\u00a0acteurs-chercheurs\u00a0\u00bb d\u2019ouvrir de nouveaux espaces d\u2019une pens\u00e9e autonome et complexe susceptible de mettre en dialectique la relation entre la multitude et la totalit\u00e9, l&rsquo;individu et le collectif, l\u2019\u00e9prouv\u00e9 et le rationnel, le sensible et l&rsquo;intelligible. Ce faisant, nous contribuons \u00e0 r\u00e9g\u00e9n\u00e9rer un d\u00e9bat public dont la d\u00e9gradation est chaque jour un peu plus marqu\u00e9e.<\/p>\n<p>Partant du principe que les sciences sociales ne se situent pas en dehors de la soci\u00e9t\u00e9, mais au contraire au c\u0153ur des rapports sociaux et qu&rsquo;elles doivent s&rsquo;ouvrir largement aux apports de tous les autres champs producteurs de savoirs et de cr\u00e9ation intellectuelle et artistique, le Laboratoire d&rsquo;Innovation Sociale par la Recherche-Action participe de cette tentative \u00e0 travers l\u2019ouverture de \u00ab\u00a0labos sociaux\u00a0\u00bb port\u00e9s par des acteurs adoptant une d\u00e9marche r\u00e9flexive. Il n\u2019est pas en cela \u00ab\u00a0pr\u00e9curseur\u00a0\u00bb ou \u00ab\u00a0\u00e9claireur\u00a0\u00bb, mais simplement en phase avec des mouvements situationnels (zones autonomes temporaires de type ZAD ou \u00ab\u00a0Occupy\u00a0\u00bb, ateliers d\u2019auto-fabrications et d\u2019exp\u00e9rimentation de type DIY, fab-lab, r\u00e9seaux d\u2019\u00e9co-d\u00e9veloppent translocal en \u00ab\u00a0d\u00e9c\u00e9l\u00e9ration\u00a0\u00bb et \u00ab\u00a0d\u00e9croissance\u00a0\u00bb de type circuit-court, tiers-lieux, agriculture urbaine, nouvelles ma\u00eetrises d\u2019usage de l\u2019espace public, etc., etc.). Ces espaces d\u2019implication ne sont pas en marges, mais au centre par l\u2019interstice qu\u2019ils occupent au c\u0153ur des territoires et des structures. Ils portent des processus profond\u00e9ment instituants. Bien que restant souvent dans l\u2019angle mort de la connaissance pour les raisons d\u00e9j\u00e0 \u00e9voqu\u00e9es, la friction de ces contres-espaces est toujours porteuse de sens et riche d\u2019exp\u00e9rience. C&rsquo;est en soutenant ces exp\u00e9rimentations et leur capacit\u00e9 \u00e0 rendre compte de leur r\u00e9alit\u00e9 qu&rsquo;il est maintenant urgent de proc\u00e9der.<\/p>\n<p>Ainsi, la pratique de recherche\/action appara\u00eet d\u00e9j\u00e0 comme un outil de r\u00e9g\u00e9n\u00e9rescence des pratiques \u00e9ducatives et sociales, aujourd&rsquo;hui enlis\u00e9es dans les institutions socio-\u00e9ducatives:<\/p>\n<ul>\n<li>Protection de l&rsquo;enfance \u00e0 l&rsquo;\u00e9preuve des mineurs isol\u00e9s, des enfants roms, dont les pratiques, mais aussi les r\u00e9f\u00e9rences th\u00e9oriques sont actuellement en panne face \u00e0 de nouvelles r\u00e9alit\u00e9s sociales\u00a0;<\/li>\n<li>Institutions de l&rsquo;\u00e9ducation sp\u00e9cialis\u00e9e de plus en plus incapables d&rsquo;int\u00e9grer les jeunes en situation de handicap qui leur sont confi\u00e9s (dans une soci\u00e9t\u00e9 qui n&rsquo;ins\u00e8re plus grand monde) et qui se retrouvent confront\u00e9es \u00e0 la question du sens de leur action\u00a0;<\/li>\n<li>Institution scolaire elle-m\u00eame de plus en plus en danger de ne se r\u00e9duire plus qu&rsquo;\u00e0 la pratique de sa propre \u00e9valuation, \u00e0 force de rejeter tout ce qui est \u00e9ducatif, culturel et artistique en dehors d&rsquo;elle-m\u00eame\u00a0;<\/li>\n<li>\u00a0 Structures n\u00e9es de l&rsquo;\u00e9ducation populaire de plus en plus assign\u00e9es aux loisirs d&rsquo;une frange de la population de moins en moins populaire\u00a0; pratiques du secteur social, de l&rsquo;insertion \u00e0 l&rsquo;\u00e9preuve d&rsquo;une pr\u00e9carisation tous azimuts de leurs publics.<\/li>\n<\/ul>\n<p>C&rsquo;est en dehors de ces institutions n\u00e9es et d\u00e9finies dans un autre contexte historique, social et \u00e9conomique, que nous entrevoyons quelques principes pour une intervention sociale et \u00e9ducative pertinente \u00e0 l&rsquo;heure de la globalit\u00e9, du num\u00e9rique et de la pr\u00e9carit\u00e9.<\/p>\n<p>Dans le domaine du travail, les ch\u00f4meurs sont trait\u00e9s de resquilleurs-profiteurs. Ces \u00ab\u00a0invisibles n&rsquo;apparaissent que comme statistique alors que ne sont jamais valoris\u00e9es les strat\u00e9gies de contournement cr\u00e9ateur de richesse. M\u00eame l\u2019\u00e9conomie sociale et solidaire plus classique n&rsquo;appara\u00eet toujours pas comme une alternative \u00e0 l\u2019entrepreneuriat capitaliste comme le montre le sabordage actuel du secteur associatif pourtant g\u00e9n\u00e9rateur d&#8217;emplois. Le discours tr\u00e8s \u00e0 la mode de l\u2019 \u00ab\u00a0empowerment\u00a0\u00bb et de la \u00ab\u00a0participation\u00a0\u00bb est d&rsquo;abord celui d&rsquo;une invitation \u00e0 la servitude volontaire et g\u00e9n\u00e8re nombre d&rsquo;injonctions paradoxales car ceux qui le promeuvent ne font que pr\u00e9server leur pouvoir.<\/p>\n<p>Cette violence symbolique, \u00e9conomique et sociale continuera tant que ne se rejoindront dans les m\u00eames luttes les diff\u00e9rentes pr\u00e9carit\u00e9s des travailleurs de l\u2019humain, de la recherche et de la cr\u00e9ation comme le fut \u00e0 certaines p\u00e9riodes le mouvement des intermittents.<\/p>\n<p>Il s\u2019agit donc d&rsquo;une part de concevoir des strat\u00e9gies d\u2019\u00e9vitement du \u00ab\u00a0bruit\u00a0\u00bb communicationnel pour r\u00e9investir syst\u00e9matiquement l\u2019espace public en adoptant une posture \u00ab\u00a0indisciplin\u00e9e\u00a0\u00bb au sens propre, c\u2019est-\u00e0-dire transdisciplinaire \u00e9chappant aux cat\u00e9gories mentales et institutionnelles de construction normative du savoir. D&rsquo;autre part, il s&rsquo;agit de favoriser des \u00ab\u00a0lieux du commun\u00a0\u00bb o\u00f9 une diversit\u00e9 et une interd\u00e9pendance peuvent se d\u00e9plier et s\u2019envelopper dans une logique \u00e9cosyst\u00e9mique. Ces lieux existent d\u00e9j\u00e0. Cr\u00e9ativit\u00e9 et intelligence sociale s&rsquo;y rejoignent pour produire de nouvelles connaissances en initiant de nouvelles pratiques.<\/p>\n<p>Cette position est d\u2019autant plus juste qu\u2019il n\u2019existe pas d\u2019acad\u00e9misme pur. L\u2019opposition radicale entre l\u2019instituant et l\u2019institu\u00e9 de la recherche est discutable\u00a0; ils vont de pair et vouloir se positionner en dehors du cadre institutionnel conduit parfois \u00e0 se marginaliser. C\u2019est, sans doute, sur le terrain des institutions que la recherche-action peut se d\u00e9velopper et, \u00e0 ce titre, les \u00ab\u00a0appels \u00e0 projets\u00a0\u00bb constituent un moyen d\u2019aller sur ce terrain pour que cette \u00ab\u00a0friction\u00a0\u00bb, \u00e9voqu\u00e9e plus haut, puisse produire ses effets.<\/p>\n<p>L&rsquo;institutuant et l&rsquo;institu\u00e9 sont des processus qui sont en articulation dynamique. L&rsquo;opposition est vis-\u00e0-vis d&rsquo;un rapport de domination qui est par d\u00e9finition un rapport d&rsquo;exploitation autant symbolique qu&rsquo;\u00e9conomique. La radicalit\u00e9 n\u2019est pas pour nous une posture id\u00e9ologique, c\u2019est la recherche-action qui est une \u00ab\u00a0science radicale\u00a0\u00bb \u00e0 l\u2019instar de ce que disait de l&rsquo;ethnom\u00e9thodologie Albert Ogien et Louis Qu\u00e9r\u00e9, par la position de recherche \u00e9thique, relationnelle, situationnelle et par la nature des rapports sociaux. Effectivement, la question n&rsquo;est pas de r\u00e9pondre ou non \u00e0 des APP (appels \u00e0 projets), d&rsquo;\u00eatre en marge ou dans l&rsquo;institution et la vocation du LISRA n\u2019est pas d\u2019\u00eatre un organisme de professionnalisation aux appels \u00e0 projets.<\/p>\n<p>Le probl\u00e8me c\u2019est que les logiques de production de connaissance engendrent une normativit\u00e9 en dehors du champ de la recherche lui-m\u00eame conduisant \u00e0 instrumentaliser des d\u00e9marches comme la recherche-action en simple m\u00e9thodologie d\u2019intervention participative et \u00e0 f\u00e9tichiser les dispositifs comme les APP qui alors deviennent une fin en soi comme modalit\u00e9 de perception de la r\u00e9alit\u00e9 sociale.<\/p>\n<p>L\u2019enjeu est de provoquer les conditions d\u2019une r\u00e9appropriation critique \u00e0 travers des espaces autog\u00e9r\u00e9s par des acteurs-chercheurs impliqu\u00e9es en situation qui s\u2019autonomisent dans l&rsquo;affirmation d\u2019une posture r\u00e9flexive. En cela, nos propos ne s&rsquo;appuient pas sur une attitude puriste, mais sur une \u00e9preuve de la r\u00e9flexivit\u00e9.<\/p>\n<p>Auto fabrication \u00e0 Tulle, \u00e9cole ouverte dans le 91, \u00ab\u00a0rue marchande\u00a0\u00bb sur la petite couronne parisienne, universit\u00e9 populaires des cultures urbaines, etc., ces processus en cours d\u00e9ssinent la cartographie d\u2019un monde pluriel qui d\u00e9passe la juxtaposition d\u2019exp\u00e9riences pour reformuler les liens que nous avons \u00e9voqu\u00e9s entre \u00e9laborations d\u2019une pens\u00e9e et pratiques contestatrices, critique sociale et processus d\u2019\u00e9mancipation.<\/p>\n<p>Nous pourrions en profiter pour d\u00e9gager une troisi\u00e8me voie ou un tiers espace au-del\u00e0 d\u2019une vision dichotomique entre acad\u00e9misme et cr\u00e9ation, scientificit\u00e9 et indiscipline, pour mettre en r\u00e9sonnance autrement cette dialectique. On aura compris que cette troisi\u00e8me voie ne s&rsquo;entend pas simplement d&rsquo;un point de vue scientifique, mais aussi politique, comme la n\u00e9cessaire formation d&rsquo;un corpus de connaissance susceptible de mettre des mots sur les processus d&rsquo;\u00e9mancipation, et les luttes sociales actuelles.<\/p>\n<p>Fichier joint :<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Nous repla\u00e7ons les labos en recherche-action dans l\u2019enjeu social et scientifique contemporain comme n\u00e9cessit\u00e9 d\u2019ouvrir des espaces critiques et instituant \u00e0 partir de l\u2019exp\u00e9rimentation sociale. Autrement dit, il s\u2019agit de rappeler l\u2019urgence de relier mouvement d\u2019une recherche contestatrice et luttes sociales \u00e9mergentes sur de nouveaux mod\u00e8les de pens\u00e9e, d\u2019organisation et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[2,3],"tags":[],"class_list":["post-472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-contributions"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2014\/11\/lisra-290x200.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3rD7a-7C","jetpack-related-posts":[{"id":863,"url":"https:\/\/recherche-action.fr\/labo-social\/2017\/08\/11\/recherche-action-en-laboratoire-social\/","url_meta":{"origin":472,"position":0},"title":"Recherche-action en laboratoire social","author":"Hugues Bazin","date":"11 ao\u00fbt 2017","format":false,"excerpt":"Qu\u2019est-ce que la Recherche-action ? La recherche-action est une d\u00e9marche qui peut s\u2019inscrire ou non dans un cadre professionnel, mais est toujours une recherche impliqu\u00e9e qui n\u00e9cessite un engagement de l\u2019individu dans son enti\u00e8ret\u00e9 et pas seulement dans sa \u00ab surcouche \u00bb technicienne. C\u2019est en cela aussi une d\u00e9marche existentielle.\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","block_context":{"text":"Actualit\u00e9","link":"https:\/\/recherche-action.fr\/labo-social\/category\/actualite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/08\/admin-ajax.php_.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":915,"url":"https:\/\/recherche-action.fr\/labo-social\/2018\/04\/05\/laboratoire-sociale-au-croisement-des-savoirs\/","url_meta":{"origin":472,"position":1},"title":"Laboratoire social au croisement des savoirs","author":"Hugues Bazin","date":"5 avril 2018","format":false,"excerpt":"Pr\u00e9sentation de la d\u00e9marche en laboratoire social Le Laboratoire d'Innovation Sociale par la Recherche-Action est actuellement compos\u00e9 d\u2019une trentaine d\u2019acteurs-chercheurs et de chercheurs-acteurs porteurs d\u2019exp\u00e9rimentations sociales dans diff\u00e9rentes r\u00e9gions (principalement\u00a0: Pays de la Loire, Rh\u00f4ne-Alpes, Limousin, \u00cele-de-France, PACA) Il s\u2019est constitu\u00e9 progressivement \u00e0 partir des ann\u00e9es 2000 dans la rencontre\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","block_context":{"text":"Actualit\u00e9","link":"https:\/\/recherche-action.fr\/labo-social\/category\/actualite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/04\/20150615_193733.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":215,"url":"https:\/\/recherche-action.fr\/labo-social\/2013\/12\/25\/maison-des-sciences-de-lhomme-paris-nord\/","url_meta":{"origin":472,"position":2},"title":"Maison des sciences de l&rsquo;Homme Paris Nord","author":"Hugues Bazin","date":"25 d\u00e9cembre 2013","format":false,"excerpt":"S\u00e9minaire \"Pratiques des espaces et innovation sociale dans le cadre de l'axe \"Penser la ville contemporaine\" anim\u00e9 par Alain Bertho, projets soutenus par la MSH Paris Nord \u00e0 l'issue de son appel \u00e0 projets 2009 Ce programme 2010-2011 a eu pour ambition la constitution d'un r\u00e9seau de chercheurs et d'experts\u2026","rel":"","context":"Dans &quot;Recherche collaborative&quot;","block_context":{"text":"Recherche collaborative","link":"https:\/\/recherche-action.fr\/labo-social\/category\/recherche-collaborative\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":874,"url":"https:\/\/recherche-action.fr\/labo-social\/2017\/09\/19\/forum-debat-sur-les-espaces-demancipation-collective-et-de-transformation-sociale-st-denis\/","url_meta":{"origin":472,"position":3},"title":"Forum d\u00e9bat sur les Espaces d\u2019\u00e9mancipation collective et de transformation sociale (St Denis)","author":"Hugues Bazin","date":"19 septembre 2017","format":false,"excerpt":"Lundi 16 octobre de 9h \u00e0 13h \u00e0 l\u2019auditorium de la Maison des Sciences de l\u2019Homme Paris-Nord 20 av George Sand 93210 St-Denis la Plaine RER B La Plaine - Stade de France \u2013 M\u00b0 12 Front populaire Les acteurs-chercheurs en r\u00e9seau avec le Laboratoire d'Innovation Sociale par la Recherche-Action\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","block_context":{"text":"Actualit\u00e9","link":"https:\/\/recherche-action.fr\/labo-social\/category\/actualite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/09\/1493536_10152917920274516_3497127595583411539_o-1024x683.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/09\/1493536_10152917920274516_3497127595583411539_o-1024x683.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/09\/1493536_10152917920274516_3497127595583411539_o-1024x683.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/09\/1493536_10152917920274516_3497127595583411539_o-1024x683.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":961,"url":"https:\/\/recherche-action.fr\/labo-social\/2018\/10\/09\/production-de-savoirs-issue-de-lexperimentation-populaire-comme-levier-de-transformation-sociale\/","url_meta":{"origin":472,"position":4},"title":"Production de savoirs issue de l\u2019exp\u00e9rimentation populaire comme levier de transformation sociale","author":"Hugues Bazin","date":"9 octobre 2018","format":false,"excerpt":"\u00ab Recherche-action et \u00e9criture r\u00e9flexive : la pratique innovante des espaces comme levier de transformation sociale \u00bb Revue Cahiers de l\u2019action, 2018\/2 N\u00b0 51-52 en libre acc\u00e8s sur la plate-forme cairn.info Fruit d\u2019un an et demi d\u2019\u00e9criture collaborative entre une vingtaine d\u2019acteurs-chercheurs, ce dossier relate l\u2019exp\u00e9rience d\u2019une production originale de\u2026","rel":"","context":"Dans &quot;Ecriture r\u00e9flexive&quot;","block_context":{"text":"Ecriture r\u00e9flexive","link":"https:\/\/recherche-action.fr\/labo-social\/category\/ecriture-reflexive\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2018\/10\/Injep51-52.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":866,"url":"https:\/\/recherche-action.fr\/labo-social\/2017\/08\/09\/espaces-demancipation-et-de-transformation\/","url_meta":{"origin":472,"position":5},"title":"Espaces d\u2019\u00e9mancipation et de transformation","author":"Hugues Bazin","date":"9 ao\u00fbt 2017","format":false,"excerpt":"L\u2019\u00e9ducation populaire r\u00e9interrog\u00e9e par la recherche-action dans un travail de la culture O\u00f9 et comment s\u2019incarne le projet \u00e9mancipateur et transformateur ? Qui sont les acteurs populaires de ces mouvements ? Quels sont les dispositifs et les outils de ce processus ? Pourquoi ces acteurs ne se revendiquent pas n\u00e9cessairement\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","block_context":{"text":"Actualit\u00e9","link":"https:\/\/recherche-action.fr\/labo-social\/category\/actualite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/08\/emancipation1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/08\/emancipation1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/08\/emancipation1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/recherche-action.fr\/labo-social\/wp-content\/uploads\/sites\/3\/2017\/08\/emancipation1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/posts\/472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/comments?post=472"}],"version-history":[{"count":1,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/posts\/472\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/posts\/472\/revisions\/808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/media\/807"}],"wp:attachment":[{"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/media?parent=472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/categories?post=472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recherche-action.fr\/labo-social\/wp-json\/wp\/v2\/tags?post=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}